{"id":25,"count":2,"description":"","link":"https:\/\/liquidstudiodev.com\/laredonewcomers-dev\/tag\/macro\/","name":"Macro","slug":"macro","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/liquidstudiodev.com\/laredonewcomers-dev\/wp-json\/wp\/v2\/tags\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/liquidstudiodev.com\/laredonewcomers-dev\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/liquidstudiodev.com\/laredonewcomers-dev\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/liquidstudiodev.com\/laredonewcomers-dev\/wp-json\/wp\/v2\/posts?tags=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}